{"id":2349,"date":"2021-04-19T22:04:55","date_gmt":"2021-04-19T20:04:55","guid":{"rendered":"https:\/\/www.fpbaixemporda.com\/?p=2349"},"modified":"2021-04-19T23:13:28","modified_gmt":"2021-04-19T21:13:28","slug":"girosystem","status":"publish","type":"post","link":"https:\/\/www.fpbaixemporda.com\/es\/girosystem\/","title":{"rendered":"Girosystem"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2349\" class=\"elementor elementor-2349\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-896cf81 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"896cf81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0b9554\" data-id=\"f0b9554\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d0c83d elementor-widget elementor-widget-image\" data-id=\"5d0c83d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/elementor\/thumbs\/Girosystem-rdmn15l0ionp44ts6gmges82yt48e21lt8d5p0wfre.jpg\" title=\"Girosystem\" alt=\"Girosystem\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-921df6e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"921df6e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-29def68\" data-id=\"29def68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e42ebcb elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e42ebcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Girosystem\/@41.966684,2.8354883,17z\/data=!3m1!4b1!4m5!3m4!1s0x12bae74e5f82d6c5:0xb00bca3bd725247a!8m2!3d41.966684!4d2.837677\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parc Cient\u00edfic i Tecnol\u00f2gic de la Universitat de Girona  \u2013 Edifici Casademont A 21 | 17003 Girona<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:972241668\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">972 24 16 68<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.girosystem.com\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-laptop\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">https:\/\/www.girosystem.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Parc Cient\u00edfic i Tecnol\u00f2gic de la Universitat de Girona \u2013 Edifici Casademont A 21 | 17003 Girona 972 24 16 68 Inici<\/p>","protected":false},"author":1,"featured_media":2350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,23],"tags":[],"class_list":["post-2349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresa","category-ins-palamos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Girosystem - FP Baix Empord\u00e0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fpbaixemporda.com\/es\/girosystem\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Girosystem - FP Baix Empord\u00e0\" \/>\n<meta property=\"og:description\" content=\"Parc Cient\u00edfic i Tecnol\u00f2gic de la Universitat de Girona \u2013 Edifici Casademont A 21 | 17003 Girona 972 24 16 68 Inici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fpbaixemporda.com\/es\/girosystem\/\" \/>\n<meta property=\"og:site_name\" content=\"FP Baix Empord\u00e0\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fpbaixemporda\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T20:04:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T21:13:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2021\/04\/Girosystem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FP Baix Empord\u00e0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FP Baix Empord\u00e0\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/\"},\"author\":{\"name\":\"FP Baix Empord\u00e0\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#\\\/schema\\\/person\\\/c8423342201478822a3de3fa26b1eba6\"},\"headline\":\"Girosystem\",\"datePublished\":\"2021-04-19T20:04:55+00:00\",\"dateModified\":\"2021-04-19T21:13:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/\"},\"wordCount\":20,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Girosystem.jpg\",\"articleSection\":[\"Empresa\",\"INS Palam\u00f3s\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/\",\"url\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/\",\"name\":\"Girosystem - FP Baix Empord\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Girosystem.jpg\",\"datePublished\":\"2021-04-19T20:04:55+00:00\",\"dateModified\":\"2021-04-19T21:13:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Girosystem.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Girosystem.jpg\",\"width\":400,\"height\":300,\"caption\":\"Girosystem\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/girosystem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Girosystem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#website\",\"url\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/\",\"name\":\"FP Baix Empord\u00e0\",\"description\":\"El teu futur en bones mans\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#organization\",\"name\":\"FP Baix Empord\u00e0\",\"url\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/FP-Baix-Empord\u00e0-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/FP-Baix-Empord\u00e0-Logo.png\",\"width\":180,\"height\":117,\"caption\":\"FP Baix Empord\u00e0\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fpbaixemporda\",\"https:\\\/\\\/www.instagram.com\\\/fp_baixemporda\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fpbaixemporda.com\\\/#\\\/schema\\\/person\\\/c8423342201478822a3de3fa26b1eba6\",\"name\":\"FP Baix Empord\u00e0\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Girosystem - FP Baix Empord\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fpbaixemporda.com\/es\/girosystem\/","og_locale":"es_ES","og_type":"article","og_title":"Girosystem - FP Baix Empord\u00e0","og_description":"Parc Cient\u00edfic i Tecnol\u00f2gic de la Universitat de Girona \u2013 Edifici Casademont A 21 | 17003 Girona 972 24 16 68 Inici","og_url":"https:\/\/www.fpbaixemporda.com\/es\/girosystem\/","og_site_name":"FP Baix Empord\u00e0","article_publisher":"https:\/\/www.facebook.com\/fpbaixemporda","article_published_time":"2021-04-19T20:04:55+00:00","article_modified_time":"2021-04-19T21:13:28+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2021\/04\/Girosystem.jpg","type":"image\/jpeg"}],"author":"FP Baix Empord\u00e0","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FP Baix Empord\u00e0","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#article","isPartOf":{"@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/"},"author":{"name":"FP Baix Empord\u00e0","@id":"https:\/\/www.fpbaixemporda.com\/#\/schema\/person\/c8423342201478822a3de3fa26b1eba6"},"headline":"Girosystem","datePublished":"2021-04-19T20:04:55+00:00","dateModified":"2021-04-19T21:13:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/"},"wordCount":20,"publisher":{"@id":"https:\/\/www.fpbaixemporda.com\/#organization"},"image":{"@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2021\/04\/Girosystem.jpg","articleSection":["Empresa","INS Palam\u00f3s"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/","url":"https:\/\/www.fpbaixemporda.com\/girosystem\/","name":"Girosystem - FP Baix Empord\u00e0","isPartOf":{"@id":"https:\/\/www.fpbaixemporda.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#primaryimage"},"image":{"@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2021\/04\/Girosystem.jpg","datePublished":"2021-04-19T20:04:55+00:00","dateModified":"2021-04-19T21:13:28+00:00","breadcrumb":{"@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fpbaixemporda.com\/girosystem\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#primaryimage","url":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2021\/04\/Girosystem.jpg","contentUrl":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2021\/04\/Girosystem.jpg","width":400,"height":300,"caption":"Girosystem"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fpbaixemporda.com\/girosystem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fpbaixemporda.com\/"},{"@type":"ListItem","position":2,"name":"Girosystem"}]},{"@type":"WebSite","@id":"https:\/\/www.fpbaixemporda.com\/#website","url":"https:\/\/www.fpbaixemporda.com\/","name":"FP Baix Empord\u00e0","description":"El teu futur en bones mans","publisher":{"@id":"https:\/\/www.fpbaixemporda.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fpbaixemporda.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fpbaixemporda.com\/#organization","name":"FP Baix Empord\u00e0","url":"https:\/\/www.fpbaixemporda.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fpbaixemporda.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2020\/02\/FP-Baix-Empord\u00e0-Logo.png","contentUrl":"https:\/\/www.fpbaixemporda.com\/wp-content\/uploads\/2020\/02\/FP-Baix-Empord\u00e0-Logo.png","width":180,"height":117,"caption":"FP Baix Empord\u00e0"},"image":{"@id":"https:\/\/www.fpbaixemporda.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fpbaixemporda","https:\/\/www.instagram.com\/fp_baixemporda\/"]},{"@type":"Person","@id":"https:\/\/www.fpbaixemporda.com\/#\/schema\/person\/c8423342201478822a3de3fa26b1eba6","name":"FP Baix Empord\u00e0"}]}},"_links":{"self":[{"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/posts\/2349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/comments?post=2349"}],"version-history":[{"count":0,"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/posts\/2349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/media\/2350"}],"wp:attachment":[{"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/media?parent=2349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/categories?post=2349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpbaixemporda.com\/es\/wp-json\/wp\/v2\/tags?post=2349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}